{"id":14,"date":"2011-01-02T20:11:42","date_gmt":"2011-01-02T19:11:42","guid":{"rendered":"http:\/\/www.50-erfolgsgrundlagen.de\/blog\/?p=14"},"modified":"2023-10-08T19:33:54","modified_gmt":"2023-10-08T17:33:54","slug":"leseprobe-geschaeftsleben-vision-entwickeln","status":"publish","type":"post","link":"https:\/\/50-erfolgsgrundlagen.de\/blog\/leseprobe-geschaeftsleben-vision-entwickeln\/","title":{"rendered":"50 biblische Erfolgsgrundlagen im Gesch\u00e4ftsleben &#8211; 1. Kapitel &#8211; Vision entwickeln"},"content":{"rendered":"<p><a href=\"https:\/\/50-erfolgsgrundlagen.de\/blog\/leseprobe-geschaeftsleben-vision-entwickeln\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-header-leseprobe-b50-kapitel-01-620x185.jpg\" width=\"620\" height=\"185\"\/><\/a><br \/>\n(<em>Fotos: Bildmontagen aus Fotoarchiv von 50 Erfolgsgrundlagen &amp; WISSEN Agentur Mittelstandsberatung, <a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/b50-autor.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color:#1403fa\">Buchautor: Uwe Melzer<\/span><\/a>)<\/em><\/p>\n<h3>Ohne eine Vision geht jedes Unternehmen unter! &#8211; Es ist nur eine Frage der Zeit! Mit einer Vision dagegen sichern Sie tats\u00e4chlich Ihr Unternehmen langfristig! Deshalb? &#8211; welche Vision hat Ihr Unternehmen?<\/h3>\n<h2><strong><a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/b50-leseprobe-01.html\" target=\"_blank\" rel=\"noopener\">Was ist eine Vision?<\/a><\/strong><\/h2>\n<p>\nVisionen haben Hochkonjunktur. Firmen, die noch keine haben, erfinden eine. Die Folge sind wundersch\u00f6ne Hochglanzbrosch\u00fcren mit beeindruckenden Fotos und eing\u00e4ngigen Texten. Das Ganze zieht sich je nach Prestigewert \u00fcber 20 bis 50 Seiten hin. Es beeindruckt die Aktion\u00e4re! Aber beeindruckt es auch Sie, Ihre Mitarbeiter, Ihre Lieferanten und Ihre Kunden? &#8211; NEIN!<\/p>\n<p><strong>Eine Vision ist das, was Sie als oberstes Ziel im Leben oder in Ihrem Unternehmen erreichen wollen. Eine Vision geht weit \u00fcber ein Ziel hinaus. Eine Vision hat in der Regel wenig mit Ihrem jetzigen privaten und gesch\u00e4ftlichen Zustand zu tun. Eine Vision ist in der Regel auch etwas, das weit in der Zukunft liegt. Zum Beispiel hatte die von Kinderl\u00e4hmung geplagte Wilma Rudolph, obwohl sie zu diesem Zeitpunkt als Kind nicht laufen konnte und ihre Beine gel\u00e4hmt waren, die Vision Olympiasiegerin zu werden. Hier in K\u00fcrze ihre Geschichte als Beweis f\u00fcr eine Vision, die Realit\u00e4t wurde, obwohl eigentlich jegliche Grundlage dazu fehlte.<\/strong><\/p>\n<p><strong>Wilma Glodean Rudolph <\/strong>wird am 23. Juni 1940 in St. Bethlehem, Clarksville\/Tennessee als 20. von 22 Kindern geboren. Ihre Mutter Blanche arbeitet als Hausm\u00e4dchen bei wei\u00dfen Familien, ihr Vater Ed ist ein einfacher Arbeiter bei der Eisenbahn. Die Familie ist arm, aber die starke religi\u00f6se Bindung und das Leben in ihrer farbigen Gemeinde helfen die allt\u00e4gliche Not zu ertragen. Wilma kommt zu fr\u00fch zur Welt und wiegt nur viereinhalb Pfund. Sie ist h\u00e4ufig krank, \u00fcbersteht eine schwere Lungenentz\u00fcndung, Scharlach und erkrankt mit vier Jahren an Kinderl\u00e4hmung. Das rechte Bein und der rechte Fu\u00df sind gel\u00e4hmt. In den &#8222;wei\u00dfen&#8220; Krankenh\u00e4usern der S\u00fcdstaaten versorgt man keine schwarzen Patienten, so bleibt nur ein schwarzer Arzt, der Wilma f\u00fcr wenig Geld behandelt. Eine Klinik im 90 Meilen entfernten Nashville hilft mit einer Spezialmassage, die ihre Mutter und ihre Geschwister mehrmals t\u00e4glich an ihr anwenden.<\/p>\n<p>Nach drei Jahren kann Wilma mit Hilfe einer Kr\u00fccke laufen. Mit elf Jahren wirft sie die Kr\u00fccke weg und ist geheilt. Wilma lernt in ihrer Schule Basketball zu spielen &#8211; sie lernt schnell. In einem Trainingscamp entdeckt der Coach Ed Temple ihr Lauftalent. Sie trainiert hart und qualifiziert sich als 16-J\u00e4hrige f\u00fcr die Olympischen Spiele in Melbourne\/Australien. Sie gewinnt mit ihrer Mannschaft die Bronzemedaille. 1958 beginnt sie ihr Studium am College der Tennessee State University und wird Mitglied der von Ed Temple trainierten &#8222;Tigerbells&#8220;. Sie ist 19 als sie sich f\u00fcr die Olympischen Spiele mit einem neuen Weltrekord \u00fcber 200 m qualifiziert.<\/p>\n<p><strong>W\u00e4hrend der Olympischen Spiele in Rom 1960 gewinnt Wilma Rudolph drei Mal Gold f\u00fcr die USA. Sie siegt \u00fcber 100 und 200 m und gewinnt mit der US-Sprintstaffel die 4 x 100 m.<\/strong> Wilma Rudolph, das ehemals schwache, kleine M\u00e4dchen, das jahrelang nur mit Hilfe einer Kr\u00fccke gehen konnte, war die schnellste Frau der Welt geworden. \u00dcberall in der Welt begeistert Wilma Rudolph die Menschen mit ihrer warmherzigen und anmutigen Ausstrahlung. In den USA wird die dreifache Olympiasiegerin als Heldin gefeiert. Das ist das Ergebnis, was aus einer Vision werden kann.<\/p>\n<h3>Eine Vision ist kein Wunsch oder ein Ziel, sondern das Erreichen einer ganz bestimmten geistlichen Vorstellung, die ich f\u00fcr mein Leben oder mein Unternehmen habe.<\/h3>\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/50-erfolgsgrundlagen.de\/grafik-wp-strich-rot-620x10.gif\" width=\"620\" height=\"10\" class=\"alignnone size-medium\"\/><br \/>\n<a href=\"https:\/\/www.minus-plus.de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/50-erfolgsgrundlagen.de\/foto-vom-minus-zum-plus-250x174.jpg\" width=\"250\" height=\"174\"\/><\/a><strong>Vom MINUS zum PLUS!<\/strong> Das ist Ihre Chance! Gott sagt, er liebt Sie, er verliert Sie nie aus den Augen. Der Glaube ist da f\u00fcr das Unm\u00f6gliche! <strong><a href=\"https:\/\/ichthys-consulting.de\/blog\/lesen-sie-den-weltweit-erfolgreichsten-buch-bestseller-was-ist-die-bibel\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #1403fa;\">Bibel<\/span><\/a><\/strong>, Neues Testament, Matth\u00e4us 11,5-6 + Lukas 7,22-23: Blinde sehen und Lahme gehen, Auss\u00e4tzige werden rein und Taube h\u00f6ren, Tote stehen auf, und Armen wird das Evangelium gepredigt; und selig ist, wer sich nicht an mir \u00e4rgert. Alle die zu Jesus Christus im neuen Testament der Bibel kamen wurden geheilt. Das ist auch heute noch die Botschaft an die Menschheit. <strong>Am tiefsten Punkt unserer Not setzt das Evangelium von Jesus Christus an. Jesus sah sein Leben als eine Befreiungsaktion. Er sagte, er sei gekommen, \u201czu suchen und zu retten, was verloren ist\u201d.<\/strong> Er selbst hat auch gesagt, dass sein Tod kein Unfall war. Er kam, um zu sterben: \u201cDes Menschen Sohn kam nicht, um sich dienen zu lassen, sondern um zu dienen und sein Leben f\u00fcr viele hinzugeben.\u201d <strong><a href=\"https:\/\/www.minus-plus.de\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #1403fa;\">https:\/\/www.minus-plus.de<\/span><\/a><\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/50-erfolgsgrundlagen.de\/grafik-wp-strich-rot-620x10.gif\" width=\"620\" height=\"10\" class=\"alignnone size-medium\"\/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gehen Sie das Risiko ein, dass sich Ihr Unternehmen, Ihre Mitarbeiter, Sie pers\u00f6nlich und Ihre Familie positiv ver\u00e4ndern. Einfach Zeit nehmen, selber lesen und anwenden. Sie werden Erstaunliches an sich selbst und Ihrer Umgebung erfahren.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/download-flyer-buch-50-biblische-erfolgsgrundlagen-im-geschaeftsleben.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/foto-wp-buch-50-erfolgsgrundlagen-verkaufsflyer-150x187.jpg\" width=\"150\" height=\"187\"\/><\/a><strong><a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/download-flyer-buch-50-biblische-erfolgsgrundlagen-im-geschaeftsleben.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000080\">Kostenloser Download Verkaufsflyer<\/span><\/a> f\u00fcr Buch 50 biblische Erfolgsgrundlagen im Gesch\u00e4ftsleben zum Verteilen und zur Weiterempfehlung!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Buch<\/strong> mit der <strong><a href=\"https:\/\/www.epubli.de\/shop\/buch\/50-biblische-Erfolgsgrundlagen-im-Gesch%C3%A4ftsleben-Uwe-Melzer-9783756537334\/130476\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000080\">ISBN 978-3-756537-33-4<\/span><\/a><\/strong> erh\u00e4ltlich im <strong><a href=\"https:\/\/www.epubli.de\/shop\/autor\/Uwe-Melzer\/2518\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000080\">epubli Verlag<\/span><\/a><\/strong>, und im Buchhandel, Amazon.de (Apple Books \/ Kindle) und anderen Verkaufspartnern: Format <strong>eBook \/ ePUB<\/strong> <strong><a href=\"https:\/\/www.epubli.de\/shop\/buch\/50-biblische-Erfolgsgrundlagen-im-Gesch%C3%A4ftsleben-Uwe-Melzer-9783756538256\/130568\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000080\">ISBN: 978-3-756538-25-6<\/span><\/a><\/strong> f\u00fcr alle mobilen Endger\u00e4te. <strong><a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/b50-leseprobe.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000080\">&gt;&gt;&gt;Leseprobe<\/span><\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ichthys-consulting.de\/grafik-wp-strich-rot-620x10.gif\" width=\"620\" height=\"10\" class=\"alignnone size-medium\"\/><br class=\"clear\"\/>\n<a href=\"https:\/\/www.epubli.de\/shop\/autor\/Uwe-Melzer\/2518\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligleft size-medium\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-flyer-epubli-buch-kaufen-290x112.png\" width=\"290\" height=\"112\"\/><\/a><a href=\"https:\/\/www.epubli.de\/shop\/buch\/50-biblische-Erfolgsgrundlagen-im-Gesch%C3%A4ftsleben-Uwe-Melzer-9783756538256\/130568\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-flyer-epubli-ebook-kaufen-290x112.png\" width=\"290\" height=\"112\"\/><\/a><br class=\"clear\"\/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ichthys-consulting.de\/grafik-wp-strich-rot-620x10.gif\" width=\"620\" height=\"10\" class=\"alignnone size-medium\"\/><br class=\"clear\"\/>\n<strong>Buch im PDF Format 13,99 \u20ac kaufen Sie direkt \u00fcber den Autor mit diesem Link: <a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/b50-kontakt.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000080\">https:\/\/www.50-erfolgsgrundlagen.de<\/span><\/a><\/strong><br class=\"clear\"\/>\n<br class=\"clear\"\/>\n<strong>Buch \/ eBook \/ ePUB ist international auch auf diesen Verkaufsplattformen erh\u00e4ltlich:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>\n<a href=\"https:\/\/www.epubli.com\/autoren\/uwe-melzer-2518\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-epubli-150x51.jpg\" width=\"150\" height=\"51\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.epubli.com\/shop\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben-9783756537334\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;Buch<\/a> \/ <a href=\"https:\/\/www.epubli.com\/shop\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben-9783756538256\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.amazon.de\/50-biblische-Erfolgsgrundlagen-Gesch%C3%A4ftsleben-Handb%C3%BCcher-ebook\/dp\/B0BJ9PY1S9\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-amazon-de-150x63.jpg\" width=\"150\" height=\"63\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.amazon.de\/50-biblische-Erfolgsgrundlagen-Gesch%C3%A4ftsleben-Handb%C3%BCcher-ebook\/dp\/B0BJ9PY1S9\/\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a> \/ <a href=\"https:\/\/www.amazon.de\/50-biblische-Erfolgsgrundlagen-Gesch%C3%A4ftsleben-Handb%C3%BCcher\/dp\/3756537331\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;Buch<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/books.apple.com\/de\/book\/50-biblische-erfolgsgrundlagen-im-gesch%C3%A4ftsleben\/id6443860315\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-apple-books-150x74.jpg\" width=\"150\" height=\"74\"\/><\/a><strong> <div align=\"center\"><a href=\"https:\/\/books.apple.com\/de\/book\/50-biblische-erfolgsgrundlagen-im-gesch%C3%A4ftsleben\/id6443860315\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a><\/div><\/strong><\/td> <td><a href=\"https:\/\/books.google.de\/books?id=LV2VEAAAQBAJ&amp;newbks=0&amp;redir_esc=y\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-google-books-150x50.jpg\" width=\"150\" height=\"50\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/books.google.de\/books?id=LV2VEAAAQBAJ&amp;newbks=0&amp;redir_esc=y\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a><\/strong><\/div><\/td><\/tr><tr><td><a href=\"https:\/\/www.weltbild.de\/artikel\/ebook\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben_39223838-1\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-weltbild-de-150x43.jpg\" width=\"150\" height=\"43\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.weltbild.de\/artikel\/ebook\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben_39223838-1\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a> \/ <a href=\"https:\/\/www.weltbild.ch\/artikel\/ebook\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben_39223838-1\" target=\"_blank\" rel=\"noopener noreferrer\">Schweiz<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.buecher.de\/shop\/glaube\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben-ebook-epub\/melzer-uwe\/products_products\/detail\/prod_id\/66111679\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-buecher-de150x50.jpg\" width=\"150\" height=\"50\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.buecher.de\/shop\/glaube\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben-ebook-epub\/melzer-uwe\/products_products\/detail\/prod_id\/66111679\/\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a> \/ <a href=\"https:\/\/www.buecher.de\/shop\/buecher\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben\/melzer-uwe\/products_products\/detail\/prod_id\/66024983\/\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;Buch<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.kobo.com\/de\/de\/ebook\/50-biblische-erfolgsgrundlagen-im-geschaftsleben-2\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-kobo-150x50.jpg\" width=\"150\" height=\"50\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.kobo.com\/de\/de\/ebook\/50-biblische-erfolgsgrundlagen-im-geschaftsleben-2\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.hoebu.de\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben-uwe-melzer-1147029\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-hoebu-de-150x50.jpg\" width=\"150\" height=\"50\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.hoebu.de\/50-biblische-erfolgsgrundlagen-im-geschaeftsleben-uwe-melzer-1147029\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a><\/strong><\/div><\/td><\/tr><tr><td><a href=\"https:\/\/www.booklooker.de\/B%C3%BCcher\/Uwe-Melzer+50-biblische-Erfolgsgrundlagen-im-Gesch%C3%A4ftsleben\/id\/A02Az8ke01ZZi\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-booklooker-de-150x50.jpg\" width=\"150\" height=\"50\"\/><\/a> <div align=\"center\"><strong> <a href=\"https:\/\/www.booklooker.de\/B%C3%BCcher\/Uwe-Melzer+50-biblische-Erfolgsgrundlagen-im-Gesch%C3%A4ftsleben\/id\/A02Az8ke01ZZi\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;Buch<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.barnesandnoble.com\/w\/50-biblische-erfolgsgrundlagen-im-gesch-ftsleben-uwe-melzer\/1113459101\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-barnes-noble-150x51.jpg\" width=\"150\" height=\"51\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.barnesandnoble.com\/w\/50-biblische-erfolgsgrundlagen-im-gesch-ftsleben-uwe-melzer\/1113459101\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a> \/ <a href=\"https:\/\/www.barnesandnoble.com\/w\/50-biblische-erfolgsgrundlagen-im-gesch-ftsleben-uwe-melzer\/1113459101\" target=\"_blank\" rel=\"noopener noreferrer\">USA<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.bol.com\/nl\/nl\/p\/50-biblische-erfolgsgrundlagen-im-geschaftsleben\/9300000126910659\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-bol-com-150x63.jpg\" width=\"150\" height=\"63\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.bol.com\/nl\/nl\/p\/50-biblische-erfolgsgrundlagen-im-geschaftsleben\/9300000126910659\/\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a> \/ <a href=\"https:\/\/www.bol.com\/nl\/nl\/p\/50-biblische-erfolgsgrundlagen-im-geschaftsleben\/9300000126910659\/\" target=\"_blank\" rel=\"noopener noreferrer\">Holland<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.lovelybooks.de\/autor\/Uwe-Melzer\/50-biblische-Erfolgsgrundlagen-im-Gesch%C3%A4ftsleben-Visionen-Ziele-Tr%C3%A4umen-Glauben-und-mehr-aus-einem-der-besten-Know-how-Handb%C3%BCcher-der-Welt-7112213075-w\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-lovelybooks-150x50.jpg\" width=\"150\" height=\"50\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.lovelybooks.de\/autor\/Uwe-Melzer\/50-biblische-Erfolgsgrundlagen-im-Gesch%C3%A4ftsleben-Visionen-Ziele-Tr%C3%A4umen-Glauben-und-mehr-aus-einem-der-besten-Know-how-Handb%C3%BCcher-der-Welt-7112213075-w\/\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a><\/strong><\/div><\/td><\/tr><tr><td><\/td><td><a href=\"https:\/\/www.frauhofer.at\/item\/58395737\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-frauhofer-at-150x65.jpg\" width=\"150\" height=\"65\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.frauhofer.at\/item\/58395737\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook \/ Buch AT<\/a><\/strong><\/div><\/td> <td><a href=\"https:\/\/www.ibs.it\/50-biblische-erfolgsgrundlagen-im-geschaftsleben-ebook-inglese-uwe-melzer\/e\/9783756538256\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-logo-fla-feltrinelli-ibs-it-150x63.jpg\" width=\"150\" height=\"63\"\/><\/a> <div align=\"center\"><strong><a href=\"https:\/\/www.ibs.it\/50-biblische-erfolgsgrundlagen-im-geschaftsleben-ebook-inglese-uwe-melzer\/e\/9783756538256\" target=\"_blank\" rel=\"noopener noreferrer\">&gt;eBook<\/a> \/ <a href=\"https:\/\/www.ibs.it\/50-biblische-erfolgsgrundlagen-im-geschaftsleben-ebook-inglese-uwe-melzer\/e\/9783756538256\" target=\"_blank\" rel=\"noopener noreferrer\">Italien<\/a><\/strong><\/div><\/td><\/tr><\/tbody><\/table><strong>Sie k\u00f6nnen das gedruckte Buch auch in jeder Buchhandlung oder in jedem Buchladen in Deutschland, \u00d6sterreich und der Schweiz kaufen mit der ISBN-Nr: 978-3-756537-33-4 als Softcover DIN A4 mit 177 Seiten.<\/strong><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ichthys-consulting.de\/grafik-wp-strich-rot-620x10.gif\" width=\"620\" height=\"10\" class=\"alignnone size-medium\"\/><br class=\"clear\"\/>\n<br class=\"clear\"\/>\n<strong><a href=\"https:\/\/www.rettung-fuer-deutschland.de\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.rettung-fuer-deutschland.de\/grafik-logo-rfd-35x35.jpg\" width=\"35\" height=\"35\"\/><\/a><\/strong><strong><a title=\"RFD Rettung f\u00fcr Deutschland\" href=\"https:\/\/www.rettung-fuer-deutschland.de\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080\">RfD Rettung f\u00fcr Deutschland<\/span><\/a><\/strong> &#8211; <a href=\"https:\/\/www.50-erfolgsgrundlagen.de\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.50-erfolgsgrundlagen.de\/grafik-wp-buch-titelseite-71x100.jpg\" width=\"71\" height=\"100\"\/><\/a>Mehr von Autor Uwe Melzer lesen Sie in diesen Presseblogs bei WordPress: <strong><a href=\"https:\/\/wissen-agentur.de\/blog\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080\">Blog Wirtschaft<\/span><\/a> &#8211; <a href=\"https:\/\/rettung-fuer-deutschland.de\/blog\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080\">Blog Politik<\/span><\/a> &#8211; <a href=\"https:\/\/50-erfolgsgrundlagen.de\/blog\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080\">Blog Erfolgsgrundlagen<\/span><\/a> &#8211; <a href=\"https:\/\/ichthys-consulting.de\/blog\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080\">Blog christliche Unternehmensberatung<\/span><\/a> &#8211; <a href=\"https:\/\/oeko-architektenhaus.de\/blog\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080\">Blog \u00f6kologischer Hausbau<\/span><\/a> &#8211; <a href=\"https:\/\/www.50-erfolgsgrundlagen.de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080\">Buch &amp; eBook &amp; ePUB: 50 Erfolgsgrundlagen<\/span><\/a><\/strong><br class=\"clear\"\/>\n<br class=\"clear\"\/>\n<a href=\"https:\/\/www.wissen-agentur.de\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/50-erfolgsgrundlagen.de\/grafik-logo-wissen-wp-308x89.jpg\" alt=\"WISSEN Agentur\" width=\"308\" height=\"89\"\/><\/a><br class=\"\u201eclear\u201c\"\/>\nE-Mail: <a href=\"mailto:info@50-erfolgsgrundlagen.de\"><span style=\"color: #000080;\">info@50-erfolgsgrundlagen.de<\/span><\/a><br class=\"\u201eclear\u201c\"\/>\nInternet: <a href=\"https:\/\/www.50-erfolgsgrundlagen.de\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080;\">www.50-erfolgsgrundlagen.de<\/span><\/a><\/p>\n\n\n<p><a class=\"twitter-share-button\" href=\"https:\/\/twitter.com\/share\" data-url=\"https:\/\/50-erfolgsgrundlagen.de\/blog\/leseprobe-geschaeftsleben-vision-entwickeln\/\" data-text=\"50 biblische #Erfolgsgrundlagen im #Gesch\u00e4ftsleben - 1. Kapitel - #Vision entwickeln:\" data-lang=\"de\">Twittern<\/a> <a href=\"https:\/\/www.xing.com\/spi\/shares\/new?follow_url=https:\/\/www.xing.com\/profile\/Uwe_Melzer2&amp;sc_p=b7910_cb&amp;url=https:\/\/50-erfolgsgrundlagen.de\/blog\/leseprobe-geschaeftsleben-vision-entwickeln\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/50-erfolgsgrundlagen.de\/grafik-xing-button-60x20.jpg\" alt=\"\" border=\"0\"\/><\/a> <script src=\"\/\/platform.linkedin.com\/in.js\" type=\"text\/javascript\">lang: de_DE<\/script><script type=\"IN\/Share\" data-url=\"https:\/\/50-erfolgsgrundlagen.de\/blog\/leseprobe-geschaeftsleben-vision-entwickeln\/\"><\/script><\/p>\n<div class=\"fb-like\" data-href=\"https:\/\/50-erfolgsgrundlagen.de\/blog\/leseprobe-geschaeftsleben-vision-entwickeln\/\" data-width=\"200\" data-layout=\"\" data-action=\"\" data-size=\"\" data-share=\"true\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Was ist eine Vision? Visionen haben Hochkonjunktur. Firmen, die noch keine haben, erfinden eine. Die Folge sind wundersch\u00f6ne Hochglanzbrosch\u00fcren mit beeindruckenden Fotos und eing\u00e4ngigen Texten. Das Ganze zieht sich je nach Prestigewert \u00fcber 20 bis 50 Seiten hin. Es beeindruckt die Aktion\u00e4re! Aber beeindruckt es auch Sie, Ihre Mitarbeiter, Ihre Lieferanten und Ihre Kunden? &#8211; NEIN! Eine Vision ist das, was sie als oberstes Ziel im Leben oder in ihrem Unternehmen erreichen wollen. Eine Vision geht weit \u00fcber ein Ziel hinaus. Eine Vision hat in der Regel wenig mit ihrem jetzigen privaten und gesch\u00e4ftlichen Zustand zu tun. Eine Vision ist in der Regel auch etwas, was weit in der Zukunft liegt. Zum Beispiel hatte die von Kinderl\u00e4hmung geplagte Wilma Rudolph, obwohl sie zu diesem Zeitpunkt als Kind nicht laufen konnte und ihre Beine gel\u00e4hmt waren, die Vision Olympiasiegerin zu werden. Hier in k\u00fcrze ihre Geschichte als Beweis f\u00fcr eine Vision, die Realit\u00e4t wurde, obwohl eigentlich jegliche Grundlage dazu gefehlt hat. \u2026. vollst\u00e4ndigen Artikel lesen bei WordPress: https:\/\/50-erfolgsgrundlagen.de\/blog\/leseprobe-geschaeftsleben-vision-entwickeln\/<\/p>\n","protected":false},"author":23904,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,2695,5,18,6,7,13,15,19,14,53,17,12,20,10,16],"tags":[30,1723,3119,31,2416,3122,2433,26,1634,3121,2419,2430,3120,2432,1722,100,48,3123,50],"class_list":["post-14","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-bibel","category-buch","category-download","category-ebook","category-erfolgsgrundlagen","category-firma","category-fuehrung","category-geschaft","category-geschaeftsleben","category-glauben","category-leseprobe","category-manager","category-selbstaendige","category-unternehmer","category-wirtschaft","tag-30","tag-amazon-de","tag-apple-books","tag-biblische","tag-buch","tag-buchhandel","tag-download","tag-ebook-2","tag-epub","tag-epubli-verlag","tag-erfolgsgrundlagen","tag-geschaeftsleben","tag-kindle","tag-leseprobe","tag-pdf","tag-unternehmen","tag-vision","tag-wunsch","tag-ziel"],"_links":{"self":[{"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/posts\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/users\/23904"}],"replies":[{"embeddable":true,"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":0,"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/posts\/14\/revisions"}],"wp:attachment":[{"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/media?parent=14"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/categories?post=14"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/50-erfolgsgrundlagen.de\/blog\/wp-json\/wp\/v2\/tags?post=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}